{"id":7517,"date":"2024-03-06T05:06:04","date_gmt":"2024-03-06T08:06:04","guid":{"rendered":"http:\/\/www.fcv.unlp.edu.ar\/?p=7517"},"modified":"2024-03-06T05:06:07","modified_gmt":"2024-03-06T08:06:07","slug":"direccion-de-tecnologia-educativa","status":"publish","type":"post","link":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/institucional\/direccion-de-tecnologia-educativa\/","title":{"rendered":"DIRECCI\u00d3N DE TECNOLOG\u00cdA EDUCATIVA"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>Asesora a los docentes acerca de los diferentes recursos mediados por tecnolog\u00edas disponibles en las modalidades presencial y virtual.<\/li>\n\n\n\n<li>Promueve la innovaci\u00f3n en las pr\u00e1cticas educativas mediante la colaboraci\u00f3n en las asignaturas para la detecci\u00f3n de necesidades y posibles oportunidades provistas por las herramientas tecnol\u00f3gicas.<\/li>\n\n\n\n<li>Brinda soporte t\u00e9cnico del Aula Virtual (Moodle).<\/li>\n\n\n\n<li>Genera material y recursos did\u00e1cticos en distintos soportes multimediales institucionales en vinculaci\u00f3n con cursos de la Facultad u otras Unidades Acad\u00e9micas y\/o convenios externos.<\/li>\n\n\n\n<li>Potencia las competencias digitales de los docentes integrando las Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n (TIC) en el proceso de ense\u00f1anza y aprendizaje.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"elearning_container_layout":"tg-site-layout--default","elearning_sidebar_layout":"tg-site-layout--default","elearning_remove_content_margin":false,"elearning_sidebar":"default","elearning_transparent_header":"customizer","elearning_logo":0,"elearning_header_style":"default","elearning_menu_item_color":"","elearning_menu_item_hover_color":"","elearning_menu_item_active_color":"","elearning_menu_item_active_style":"","elearning_page_header":true,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[42,10],"tags":[],"class_list":["post-7517","post","type-post","status-publish","format-standard","hentry","category-direcciones","category-institucional"],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:00:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7517"}],"version-history":[{"count":1,"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7517\/revisions"}],"predecessor-version":[{"id":7518,"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7517\/revisions\/7518"}],"wp:attachment":[{"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcv.unlp.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}